{"id":16717,"date":"2026-07-06T14:25:20","date_gmt":"2026-07-06T06:25:20","guid":{"rendered":"https:\/\/auto-state.com\/product\/motocross-brake-pedal-asb-asb-140f\/"},"modified":"2026-07-13T17:05:57","modified_gmt":"2026-07-13T09:05:57","slug":"motocross-brake-pedal-asb-asb-140f","status":"publish","type":"product","link":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/","title":{"rendered":"Motocross Brake Pedal ASB-140F"},"content":{"rendered":"<p>For KTM (XC)<br \/>\n200 XC-W 2015-2016<br \/>\n450 XC-W 2008-2010<br \/>\n505 XC-F 2009<br \/>\n530 XCR-W 2008<br \/>\n530 XC-W 2009-2010<br \/>\nHUSQVARNA (ENDURO)<br \/>\nFE 390 2010-2012<br \/>\nFE 450 2009-2012<br \/>\nFE 570 2009-2012<br \/>\nHUSQVARNA (XC)<br \/>\nFX 450 2010-2011<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Model: ASB-140F<br \/>\nCountry of Origin: Taiwan<br \/>\nMaterial: aluminum alloy<\/p>\n","protected":false},"featured_media":13381,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[471,429],"product_tag":[],"class_list":{"0":"post-16717","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-motocross-rear-brake-pedals-en","7":"product_cat-rear-brake-pedals-en","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"Model: ASB-140F Country of Origin: Taiwan Material: aluminum alloy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/\" \/>\n<meta property=\"og:site_name\" content=\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autostateindustrial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T09:05:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/\",\"url\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/\",\"name\":\"Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/auto-state.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg\",\"datePublished\":\"2026-07-06T06:25:20+00:00\",\"dateModified\":\"2026-07-13T09:05:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage\",\"url\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg\",\"contentUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/auto-state.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/auto-state.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Motocross Brake Pedal ASB-140F\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/auto-state.com\/en\/#website\",\"url\":\"https:\/\/auto-state.com\/en\/\",\"name\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"description\":\"\u5c08\u696d\u751f\u7522\u88fd\u9020\u3001CNC\u4ee3\u5de5\u6a5f\u8eca\u7cbe\u5bc6\u96f6\u914d\u4ef6\",\"publisher\":{\"@id\":\"https:\/\/auto-state.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/auto-state.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/auto-state.com\/en\/#organization\",\"name\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/auto-state.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png\",\"contentUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png\",\"width\":1704,\"height\":420,\"caption\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/autostateindustrial\/\",\"https:\/\/www.instagram.com\/auto.state\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/","og_locale":"en_US","og_type":"article","og_title":"Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","og_description":"Model: ASB-140F Country of Origin: Taiwan Material: aluminum alloy","og_url":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/","og_site_name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","article_publisher":"https:\/\/www.facebook.com\/autostateindustrial\/","article_modified_time":"2026-07-13T09:05:57+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/","url":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/","name":"Motocross Brake Pedal ASB-140F - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","isPartOf":{"@id":"https:\/\/auto-state.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage"},"image":{"@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage"},"thumbnailUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg","datePublished":"2026-07-06T06:25:20+00:00","dateModified":"2026-07-13T09:05:57+00:00","breadcrumb":{"@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#primaryimage","url":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg","contentUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASB-140F.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/auto-state.com\/en\/product\/motocross-brake-pedal-asb-asb-140f\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/auto-state.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/auto-state.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Motocross Brake Pedal ASB-140F"}]},{"@type":"WebSite","@id":"https:\/\/auto-state.com\/en\/#website","url":"https:\/\/auto-state.com\/en\/","name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","description":"\u5c08\u696d\u751f\u7522\u88fd\u9020\u3001CNC\u4ee3\u5de5\u6a5f\u8eca\u7cbe\u5bc6\u96f6\u914d\u4ef6","publisher":{"@id":"https:\/\/auto-state.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auto-state.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/auto-state.com\/en\/#organization","name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","url":"https:\/\/auto-state.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png","contentUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png","width":1704,"height":420,"caption":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autostateindustrial\/","https:\/\/www.instagram.com\/auto.state\/"]}]}},"_links":{"self":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product\/16717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/comments?post=16717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/media\/13381"}],"wp:attachment":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/media?parent=16717"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_brand?post=16717"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_cat?post=16717"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_tag?post=16717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}