{"id":17077,"date":"2026-07-06T14:30:00","date_gmt":"2026-07-06T06:30:00","guid":{"rendered":"https:\/\/auto-state.com\/product\/foot-pegs-ii-asf-asf-228\/"},"modified":"2026-07-13T17:07:30","modified_gmt":"2026-07-13T09:07:30","slug":"foot-pegs-ii-asf-asf-228","status":"publish","type":"product","link":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/","title":{"rendered":"Foot Pegs II ASF-228"},"content":{"rendered":"<p>For TM Racing<br \/>\nEN 125 2008-2020<br \/>\nEN 144 2008-2020<br \/>\nEN 250 2008-2009<br \/>\nEN 250 Fi 2010-2020<br \/>\nEN 300 2008-2020<br \/>\nEN 300 Fi 2018-2020<br \/>\nEN 450 Fi 2011-2020<br \/>\nEN 530 Fi 2015-2020<br \/>\nMX 125 2008-2020<br \/>\nMX 144 2008-2020<br \/>\nMX 250 2008-2020<br \/>\nMX 250 Fi 2010-2020<br \/>\nMX 300 2008-2020<br \/>\nMX 300 Fi 2018-2020<br \/>\nMX 450 Fi 2011-2020<br \/>\nMX 530 Fi 2015-2020<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Model: ASF-228<br \/>\nCountry of Origin: Taiwan<br \/>\nMaterial: aluminum alloy+stainless<\/p>\n","protected":false},"featured_media":14092,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[437,510],"product_tag":[],"class_list":{"0":"post-17077","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-foot-pegs-en","7":"product_cat-foot-pegs-ii-en","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"og:description\" content=\"Model: ASF-228 Country of Origin: Taiwan Material: aluminum alloy+stainless\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/\" \/>\n<meta property=\"og:site_name\" content=\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/autostateindustrial\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T09:07:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/\",\"url\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/\",\"name\":\"Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"isPartOf\":{\"@id\":\"https:\/\/auto-state.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg\",\"datePublished\":\"2026-07-06T06:30:00+00:00\",\"dateModified\":\"2026-07-13T09:07:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage\",\"url\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg\",\"contentUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/auto-state.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/auto-state.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Foot Pegs II ASF-228\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/auto-state.com\/en\/#website\",\"url\":\"https:\/\/auto-state.com\/en\/\",\"name\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"description\":\"\u5c08\u696d\u751f\u7522\u88fd\u9020\u3001CNC\u4ee3\u5de5\u6a5f\u8eca\u7cbe\u5bc6\u96f6\u914d\u4ef6\",\"publisher\":{\"@id\":\"https:\/\/auto-state.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/auto-state.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/auto-state.com\/en\/#organization\",\"name\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\",\"url\":\"https:\/\/auto-state.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png\",\"contentUrl\":\"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png\",\"width\":1704,\"height\":420,\"caption\":\"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8\"},\"image\":{\"@id\":\"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/autostateindustrial\/\",\"https:\/\/www.instagram.com\/auto.state\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/","og_locale":"en_US","og_type":"article","og_title":"Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","og_description":"Model: ASF-228 Country of Origin: Taiwan Material: aluminum alloy+stainless","og_url":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/","og_site_name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","article_publisher":"https:\/\/www.facebook.com\/autostateindustrial\/","article_modified_time":"2026-07-13T09:07:30+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/","url":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/","name":"Foot Pegs II ASF-228 - \u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","isPartOf":{"@id":"https:\/\/auto-state.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage"},"image":{"@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage"},"thumbnailUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg","datePublished":"2026-07-06T06:30:00+00:00","dateModified":"2026-07-13T09:07:30+00:00","breadcrumb":{"@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#primaryimage","url":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg","contentUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2026\/07\/ASF-228.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/auto-state.com\/en\/product\/foot-pegs-ii-asf-asf-228\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/auto-state.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/auto-state.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Foot Pegs II ASF-228"}]},{"@type":"WebSite","@id":"https:\/\/auto-state.com\/en\/#website","url":"https:\/\/auto-state.com\/en\/","name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","description":"\u5c08\u696d\u751f\u7522\u88fd\u9020\u3001CNC\u4ee3\u5de5\u6a5f\u8eca\u7cbe\u5bc6\u96f6\u914d\u4ef6","publisher":{"@id":"https:\/\/auto-state.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auto-state.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/auto-state.com\/en\/#organization","name":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8","url":"https:\/\/auto-state.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png","contentUrl":"https:\/\/auto-state.com\/wp-content\/uploads\/2025\/12\/LOGO2.png","width":1704,"height":420,"caption":"\u532f\u6046\u6a5f\u68b0\u5be6\u696d\u80a1\u4efd\u6709\u9650\u516c\u53f8"},"image":{"@id":"https:\/\/auto-state.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/autostateindustrial\/","https:\/\/www.instagram.com\/auto.state\/"]}]}},"_links":{"self":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product\/17077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/comments?post=17077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/media\/14092"}],"wp:attachment":[{"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/media?parent=17077"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_brand?post=17077"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_cat?post=17077"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/auto-state.com\/en\/wp-json\/wp\/v2\/product_tag?post=17077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}